{"id":8341,"date":"2023-10-11T17:42:33","date_gmt":"2023-10-11T08:42:33","guid":{"rendered":"https:\/\/jikotrading.jp\/jpn\/?p=8341"},"modified":"2025-02-13T15:17:30","modified_gmt":"2025-02-13T06:17:30","slug":"b7141","status":"publish","type":"post","link":"https:\/\/jikotrading.jp\/jpn\/b7141\/","title":{"rendered":"\u30b3\u30d9\u30eb\u30b3 \u6cb9\u5727\u30b7\u30e7\u30d9\u30eb \/ SK115SR-1E"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u554f\u5408\u756a\u53f7: B-7141<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u8eca\u540d: \u30b3\u30d9\u30eb\u30b3<br>\u5e74\u5f0f:  2002\u5e74 \uff16\u6708\u3000<br>\u30e2\u30c7\u30eb: SK115SR-1E<br>SN: YV02-019XX<br>\u8eca\u4f53\u306e\u5f62\u72b6: \u6cb9\u5727\u30b7\u30e7\u30d9\u30eb<br>\u539f\u52d5\u6a5f\u306e\u578b\u5f0f: BB-4BG1T<br><br>\u30a8\u30f3\u30b8\u30f3\u6700\u9ad8\u51fa\u529b: 80H\/P<br>\u30a8\u30f3\u30b8\u30f3\u6392\u6c17\u91cf: 4,329CC<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u8eca\u4f53<br>\u5bf8\u6cd5 \u5168\u9577 6,880mm<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u5168\u5e45 2,490mm<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><p>\u5168\u9ad8 2,740mm<br>\u8eca\u8f0c\u7dcf\u91cd\u91cf: 11,800kg<br>\u30d0\u30b1\u30c3\u30c8\u5bb9\u91cf: 0.45\u33a5<br>\u7a3c\u52d5\u6642\u9593: 9,545\u6642\u9593<\/p>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/002.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/003.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/004.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/005.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/006.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/007.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/008.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/009.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/010.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/011.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/012.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/013.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/014.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/015.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/016.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/017.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/018.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/019.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/020.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/021.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/022.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/023.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/024.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/025.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/026.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/027.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/028.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/029.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/030.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/031.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/032.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/033.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/034.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/035.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/036.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/037.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/038.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/039.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/040.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/041.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/042.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/043.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/044.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/045.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/046.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/047.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/048.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/049.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/050.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/051.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/052.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/053.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/054.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/055.jpg\" \/>\n\n<img decoding=\"async\" src=\"\/img\/product\/b7141\/056.jpg\" \/>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u554f\u5408\u756a\u53f7: B-7141 \u8eca\u540d: \u30b3\u30d9\u30eb [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,3],"tags":[],"class_list":["post-8341","post","type-post","status-publish","format-standard","category-heavy-machine","category-previous-soldout"],"_links":{"self":[{"href":"https:\/\/jikotrading.jp\/jpn\/wp-json\/wp\/v2\/posts\/8341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jikotrading.jp\/jpn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jikotrading.jp\/jpn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jikotrading.jp\/jpn\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jikotrading.jp\/jpn\/wp-json\/wp\/v2\/comments?post=8341"}],"version-history":[{"count":11,"href":"https:\/\/jikotrading.jp\/jpn\/wp-json\/wp\/v2\/posts\/8341\/revisions"}],"predecessor-version":[{"id":8419,"href":"https:\/\/jikotrading.jp\/jpn\/wp-json\/wp\/v2\/posts\/8341\/revisions\/8419"}],"wp:attachment":[{"href":"https:\/\/jikotrading.jp\/jpn\/wp-json\/wp\/v2\/media?parent=8341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jikotrading.jp\/jpn\/wp-json\/wp\/v2\/categories?post=8341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jikotrading.jp\/jpn\/wp-json\/wp\/v2\/tags?post=8341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}